{"id":708,"date":"2021-10-13T10:53:55","date_gmt":"2021-10-13T10:53:55","guid":{"rendered":"https:\/\/brok.qodeinteractive.com\/?page_id=708"},"modified":"2024-09-20T10:25:03","modified_gmt":"2024-09-20T10:25:03","slug":"get-in-touch","status":"publish","type":"page","link":"https:\/\/estudiovicens.com\/es\/get-in-touch\/","title":{"rendered":"Get In Touch"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"708\" class=\"elementor elementor-708\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bdb84b elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"7bdb84b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c36461\" data-id=\"5c36461\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1611aba elementor-widget elementor-widget-brok_core_section_title\" data-id=\"1611aba\" data-element_type=\"widget\" data-widget_type=\"brok_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left\">\n\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tContacte Con<br \/> Nuestra Oficina\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf3583 elementor-widget elementor-widget-brok_core_icon_list_item\" data-id=\"3bf3583\" data-element_type=\"widget\" data-widget_type=\"brok_core_icon_list_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-icon-list-item qodef-icon--icon-pack\" >\n\t<p class=\"qodef-e-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"tel:  34 606015978\" target=\"_blank\">\n\t\t\t\t\t<span class=\"qodef-e-title-inner\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-title-text\">Tel: +34 606015978<\/span>\n\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22cd5f elementor-widget elementor-widget-brok_core_icon_list_item\" data-id=\"b22cd5f\" data-element_type=\"widget\" data-widget_type=\"brok_core_icon_list_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-icon-list-item qodef-icon--icon-pack\" >\n\t<p class=\"qodef-e-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"mailto:info@estudiovicens.com\" target=\"_blank\">\n\t\t\t\t\t<span class=\"qodef-e-title-inner\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-title-text\">info@estudiovicens.com<\/span>\n\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69e94d2 elementor-widget elementor-widget-brok_core_icon_list_item\" data-id=\"69e94d2\" data-element_type=\"widget\" data-widget_type=\"brok_core_icon_list_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-icon-list-item qodef-icon--icon-pack\" >\n\t<p class=\"qodef-e-title\" >\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/www.google.com\/maps\/search\/Avd%2FAlameda+Camilo+Sesto+82+Pasaje+03803+Alcoi+(Alicante)\/@38.7013083,-0.4808207,17z\/data=!3m1!4b1?entry=ttu&#038;g_ep=EgoyMDI0MDkxNi4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\">\n\t\t\t\t\t<span class=\"qodef-e-title-inner\">\n\t\t\t\t\t\t\t\t<span class=\"qodef-e-title-text\">Avd\/Alameda Camilo Sesto, 82 Pasaje 03803 Alcoi (Alicante)<\/span>\n\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80e2530\" data-id=\"80e2530\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fed75a elementor-widget elementor-widget-wp-widget-brok_core_contact_form_7\" data-id=\"5fed75a\" data-element_type=\"widget\" data-widget_type=\"wp-widget-brok_core_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-contact-form-7\">\n\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f361-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"361\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/wp-json\/wp\/v2\/pages\/708\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/708#wpcf7-f361-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"361\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f361-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"qodef-contact-form\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Asunto\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"1\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span>\n<button class=\"wpcf7-form-control wpcf7-submit qodef-button qodef-size--normal qodef-layout--filled qodef-html--link qodef-m\" type=\"submit\"><span class=\"qodef-m-text\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" width=\"12px\" height=\"12px\" viewbox=\"0 0 12 12\" style=\"enable-background:new 0 0 12 12;\" xml:space=\"preserve\"><g><rect y=\"5\" width=\"12\" height=\"2\"\/><rect y=\"5\" transform=\"matrix(6.123234e-17 -1 1 6.123234e-17 0 12)\" width=\"12\" height=\"2\"\/><\/g><\/svg>Enviar<\/span><\/button>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-64d7e06 e-flex e-con-boxed e-con e-parent\" data-id=\"64d7e06\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f191d2c elementor-widget elementor-widget-google_maps\" data-id=\"f191d2c\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Avd%2FAlameda%20Camilo%20Sesto%2082%20Pasaje%2003803%20Alcoi%20%28Alicante%29&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Avd\/Alameda Camilo Sesto 82 Pasaje 03803 Alcoi (Alicante)\"\n\t\t\t\t\taria-label=\"Avd\/Alameda Camilo Sesto 82 Pasaje 03803 Alcoi (Alicante)\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Contact Our Head Office Tel: +34 606015978 info@estudiovicens.com Avd\/Alameda Camilo Sesto, 82 Pasaje 03803 Alcoi (Alicante)<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-708","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/pages\/708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/comments?post=708"}],"version-history":[{"count":3,"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/pages\/708\/revisions"}],"predecessor-version":[{"id":5611,"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/pages\/708\/revisions\/5611"}],"wp:attachment":[{"href":"https:\/\/estudiovicens.com\/es\/wp-json\/wp\/v2\/media?parent=708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}